{"id":43,"date":"2021-03-10T19:40:44","date_gmt":"2021-03-10T19:40:44","guid":{"rendered":"https:\/\/warm-up.live\/?page_id=43"},"modified":"2021-04-05T10:42:09","modified_gmt":"2021-04-05T10:42:09","slug":"die-partner","status":"publish","type":"page","link":"https:\/\/warm-up.live\/index.php\/die-partner\/","title":{"rendered":"Die Partner"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/kb-gym.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/warm-up.live\/wp-content\/uploads\/2021\/03\/KBGym-1-300x300.jpg\" alt=\"\" class=\"wp-image-167\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/viehmannphotographie.de\/\" target=\"_blank\" rel=\"Viehmann Photographie noopener\"><img decoding=\"async\" src=\"https:\/\/warm-up.live\/wp-content\/uploads\/2021\/03\/KayViehmann.png\" alt=\"\" class=\"wp-image-256\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"657\" src=\"https:\/\/warm-up.live\/wp-content\/uploads\/2021\/04\/Robin-Zabel-Logo-1024x657.png\" alt=\"\" class=\"wp-image-598\" srcset=\"https:\/\/warm-up.live\/wp-content\/uploads\/2021\/04\/Robin-Zabel-Logo-1024x657.png 1024w, https:\/\/warm-up.live\/wp-content\/uploads\/2021\/04\/Robin-Zabel-Logo-300x193.png 300w, https:\/\/warm-up.live\/wp-content\/uploads\/2021\/04\/Robin-Zabel-Logo-768x493.png 768w, https:\/\/warm-up.live\/wp-content\/uploads\/2021\/04\/Robin-Zabel-Logo.png 1178w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":285,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-43","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/pages\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":12,"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"predecessor-version":[{"id":599,"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/pages\/43\/revisions\/599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/media\/285"}],"wp:attachment":[{"href":"https:\/\/warm-up.live\/index.php\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}